{"id":37357,"date":"2024-11-19T17:26:28","date_gmt":"2024-11-19T20:26:28","guid":{"rendered":"https:\/\/agilize.com.br\/blog\/?p=37357"},"modified":"2025-07-30T15:05:50","modified_gmt":"2025-07-30T18:05:50","slug":"advogado-pode-ser-mei","status":"publish","type":"post","link":"https:\/\/agilize.com.br\/blog\/abrir-sua-empresa\/advogado-pode-ser-mei\/","title":{"rendered":"Advogado pode ser MEI? Conhe\u00e7a as op\u00e7\u00f5es para atuar na \u00e1rea!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/agilize.com.br\/blog\/wp-content\/uploads\/2024\/10\/case-de-sucesso-astor-cirne-1.jpg\" alt=\"advogado pode ser mei ou nao, nao tenha mais duvidas sobre esse questionamento\" class=\"wp-image-42362\"\/><\/figure>\n\n\n\n<p>A d\u00favida &#8220;advogado pode ser MEI?&#8221; \u00e9 comum entre profissionais da advocacia que desejam <strong>formalizar suas atividades e obter os benef\u00edcios de ter um CNPJ<\/strong>.<\/p>\n\n\n\n<p>Nesse contexto, o regime de Microempreendedor Individual (MEI) oferece vantagens atrativas, como baixos custos com impostos e menos burocracia, mas ser\u00e1 que advogados podem se enquadrar nessa categoria?<\/p>\n\n\n\n<p>Vamos explorar todas as possibilidades e alternativas que esses profissionais t\u00eam para atuar formalmente no mercado. Acompanhe!<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"#Advogado-pode-ser-MEI-ou-n\u00e3o\">Advogado pode ser MEI ou n\u00e3o?<\/a><\/li>\n\n\n\n<li><a href=\"#Atividades-que-podem-ser-MEI\">Atividades que podem ser MEI<\/a><\/li>\n\n\n\n<li><a href=\"#Tipos-de-empresa-para-advogado\">Tipos de empresa para advogado<\/a><\/li>\n\n\n\n<li><a href=\"#Como-o-advogado-pode-aderir-ao-Simples-Nacional\">Como o advogado pode aderir ao Simples Nacional<\/a><\/li>\n\n\n\n<li><a href=\"#O-que-um-advogado-precisa-para-abrir-uma-empresa\">O que um advogado precisa para abrir uma empresa?<\/a><\/li>\n\n\n\n<li><a href=\"#Quais-as-vantagens-de-ter-CNPJ-como-advogado\">Quais as vantagens de ter CNPJ como advogado?<\/a><\/li>\n\n\n\n<li><a href=\"#Tenha-um-CNPJ-para-advogado-sem-burocracias\">Tenha um CNPJ para advogado sem burocracias<\/a><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Advogado-pode-ser-MEI-ou-n\u00e3o\">Advogado pode ser MEI ou n\u00e3o?<\/h2>\n\n\n\n<p>N\u00e3o, advogado n\u00e3o pode ser MEI. Mas aten\u00e7\u00e3o!<\/p>\n\n\n\n<p>O regime de Microempreendedor Individual (<a href=\"https:\/\/agilize.com.br\/blog\/empreendedorismo\/mei\/quem-pode-ser-microempreendedor-individual\/\">MEI<\/a>) foi criado para simplificar a formaliza\u00e7\u00e3o de pequenos empreendedores e aut\u00f4nomos, mas ele exclui profiss\u00f5es regulamentadas, como a advocacia.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CONTABILIDADE PARA ADVOGADOS: ENTENDA TUDO!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/SDY0HifDftU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Isso ocorre porque o MEI \u00e9 destinado a<strong> atividades de baixo risco e que n\u00e3o exigem regulamenta\u00e7\u00e3o espec\u00edfica<\/strong>.&nbsp;<\/p>\n\n\n\n<p>E profiss\u00f5es regulamentadas como advocacia, medicina, odontologia, engenharia, entre outras, possuem regras e exig\u00eancias pr\u00f3prias que n\u00e3o se encaixam nas condi\u00e7\u00f5es simplificadas do MEI.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Atividades-que-podem-ser-MEI\">Atividades que podem ser MEI<\/h2>\n\n\n\n<p>Por outro lado, o regime de Microempreendedor Individual (MEI) permite a formaliza\u00e7\u00e3o de diversas atividades voltadas para pequenos empreendedores e aut\u00f4nomos.<\/p>\n\n\n\n<p>Como vimos, as atividades permitidas para MEI s\u00e3o aquelas que envolvem presta\u00e7\u00e3o de servi\u00e7os, com\u00e9rcio e produ\u00e7\u00e3o de itens de baixo risco, n\u00e3o regulamentadas por conselhos profissionais espec\u00edficos, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Servi\u00e7os de beleza e bem-estar<\/strong>: cabeleireiro, barbeiro, esteticista, manicure e pedicure, depilador, maquiador, massagista;<\/li>\n\n\n\n<li><strong>Servi\u00e7os de manuten\u00e7\u00e3o e repara\u00e7\u00e3o<\/strong>: eletricista, encanador, pintor, pedreiro, serralheiro, chaveiro, t\u00e9cnico de manuten\u00e7\u00e3o de eletrodom\u00e9sticos;<\/li>\n\n\n\n<li><strong>Com\u00e9rcio e produ\u00e7\u00e3o de alimentos<\/strong>: vendedor de alimentos preparados (ambulante ou em local fixo), confeiteiro, pipoqueiro, sorveteiro, produtor de doces, salgados e bolos;<\/li>\n\n\n\n<li><strong>Artesanato e produ\u00e7\u00e3o manual<\/strong>: artes\u00e3o, costureira, bordadeira, tapeceiro, produtor de bijuterias, sapateiro;<\/li>\n\n\n\n<li><strong>Servi\u00e7os de transporte e entrega<\/strong>: motoboy, taxista, motorista de aplicativo, entregador de mercadorias.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Tipos-de-empresa-para-advogado\">Tipos de empresa para advogado<\/h2>\n\n\n\n<p>Existem modelos que respeitam as exig\u00eancias da Ordem dos Advogados do Brasil (OAB) e s\u00e3o compat\u00edveis com as regulamenta\u00e7\u00f5es da profiss\u00e3o. Abaixo, veja as principais op\u00e7\u00f5es para advogados:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sociedade Unipessoal de Advocacia (SUA)<\/h3>\n\n\n\n<p>A Sociedade Unipessoal de Advocacia \u00e9 uma das modalidades mais populares para advogados que desejam trabalhar sozinhos e formalizar suas atividades com um CNPJ.&nbsp;<\/p>\n\n\n\n<p>Nessa categoria, <strong>o advogado \u00e9 o \u00fanico s\u00f3cio da empresa<\/strong>, o que facilita o processo de abertura e gest\u00e3o. Al\u00e9m disso, permite a ades\u00e3o ao <a href=\"https:\/\/agilize.com.br\/blog\/gestao-fiscal\/simples-nacional\/\">Simples Nacional<\/a>, oferecendo um regime tribut\u00e1rio simplificado e reduzido.<\/p>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\">Sociedade Simples de Advogados<\/h3>\n\n\n\n<p>Por outro lado, para advogados que desejam atuar em conjunto com outros colegas de profiss\u00e3o, a Sociedade Simples de Advogados \u00e9 uma excelente op\u00e7\u00e3o.<\/p>\n\n\n\n<p>Nesse modelo, <strong>dois ou mais advogados se associam para prestar servi\u00e7os de advocacia sob um \u00fanico CNPJ<\/strong>. \u00c9 importante lembrar que a sociedade \u00e9 regida por um contrato social e precisa ser registrada junto \u00e0 OAB.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sociedade Limitada (Ltda.)<\/h3>\n\n\n\n<p>Al\u00e9m das anteriores, a Sociedade Limitada \u00e9 uma op\u00e7\u00e3o v\u00e1lida, mas \u00e9 usada principalmente por advogados que desejam<strong> atuar em uma empresa que presta servi\u00e7os diversos<\/strong>, al\u00e9m da advocacia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Como-o-advogado-pode-aderir-ao-Simples-Nacional\">Como o advogado pode aderir ao Simples Nacional<\/h2>\n\n\n\n<p>Para que o advogado possa aderir ao Simples Nacional, \u00e9 necess\u00e1rio que ele escolha uma estrutura societ\u00e1ria compat\u00edvel com a advocacia e siga alguns requisitos espec\u00edficos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Escolher a estrutura jur\u00eddica correta<\/h3>\n\n\n\n<p>Nem todas as modalidades de empresa s\u00e3o eleg\u00edveis para o Simples Nacional. Para advogados, as op\u00e7\u00f5es mais indicadas para aderir ao Simples s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sociedade Unipessoal de Advocacia (SUA)<\/strong>: permite ao advogado atuar sozinho com um CNPJ, mantendo a responsabilidade limitada e facilitando a tributa\u00e7\u00e3o;<\/li>\n\n\n\n<li><strong>Sociedade Simples de Advogados<\/strong>: permite que dois ou mais advogados atuem em conjunto sob um \u00fanico CNPJ.<\/li>\n<\/ul>\n\n\n\n<p>Ambas modalidades s\u00e3o aceitas no Simples Nacional e s\u00e3o registradas na OAB, respeitando as exig\u00eancias da profiss\u00e3o.<\/p>\n\n\n\n\t\t\t<style>\n\t\t\t\t.agz-conversion-form {\n\t\t\t\t\theight: inherit;\n\t\t\t\t\tbackground: #fff;\n\t\t\t\t\tborder-radius: 1rem;\n\t\t\t\t\tpadding: 0.5rem;\n\t\t\t\t\tcolor: #595066;\n\t\t\t\t\tfont-family: Inter,sans-serif;\n\t\t\t\t\tbox-shadow: 0 3px 20px 1px rgb(65 58 79 \/ 6%);\n\t\t\t\t\tuser-select: none;\n\t\t\t\t}\n\t\t\t\t.agz-conversion-form form{\n\t\t\t\t\tborder-radius: 0.5rem;\n\t\t\t\t\tbackground-color: #E5E2E9;\n\t\t\t\t}\n\t\t\t\t.agz-conversion-form h6{\n\t\t\t\t\tfont-size: xx-large;\n\t\t\t\t\tcolor: #7a4dbf;\n    \t\t\t\tfont-weight: 700;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t}\n\t\t\t\t.agz-conversion-form input,\n\t\t\t\t.agz-conversion-form select {\n\t\t\t\t\tborder: 1px solid #C3BDCC;\n\t\t\t\t\tborder-radius: 8px;\n\t\t\t\t\tpadding: 0.5rem 1rem;\n\t\t\t\t\toutline: 0;\n\t\t\t\t}\n\t\t\t\t.agz-conversion-form button {\n\t\t\t\t\twidth: fit-content; \n\t\t\t\t\tbackground: #26bf87;\n\t\t\t\t\ttext-transform: uppercase;\n\t\t\t\t\tbox-shadow: 0 4px 10px 1px rgb(38 191 135 \/ 15%);\n\t\t\t\t\tborder-radius: 2rem;\n\t\t\t\t\tfont-family: Inter,sans-serif;\n\t\t\t\t\tfont-weight: 700;\n\t\t\t\t\tfont-size: large;\n\t\t\t\t\tcolor: #fff;\n\t\t\t\t\talign-self: center;\n\t\t\t\t\ttransition: background .25s;\n\t\t\t\t\tcursor: pointer;\n\t\t\t\t}\n\t\t\t\t.agz-conversion-form button:hover {\n\t\t\t\t\tcolor: #fff;\n\t\t\t\t\tbackground: #5fedb9;\n\t\t\t\t\ttransition: background .25s;\n\t\t\t\t}\n\t\t\t\t.agz-conversion-form button:active {\n\t\t\t\t\toutline: 0;\n\t\t\t\t}\n\t\t\t\t#agz-conversion-form-success{\n\t\t\t\t\tborder-radius: 0.5rem;\n\t\t\t\t\tbackground-color: #7a4dbf;\n\t\t\t\t\tdisplay: none;\n\t\t\t\t}\n\t\t\t\t#agz-conversion-form-success h6, #agz-conversion-form-success p{\n\t\t\t\t\tcolor: white !important;\n\t\t\t\t}\n\t\t\t<\/style>\n\t\t\t<aside class=\"agz-conversion-form\">\n\t\t\t\t<div id=\"agz-conversion-form-success\" class=\"agz-conversion-form container p-4\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<h6 class=\"col-md-10 col-12 mx-auto p-0 mt-0\">Recebemos sua solicita\u00e7\u00e3o e em breve entraremos em contato.<\/h6>\n\t\t\t\t\t\t<p class=\"text-center mb-0 col-md-10 col-12 mx-auto p-0\">Voc\u00ea receber\u00e1 um telefonema nosso em breve. Fique de olho em liga\u00e7\u00f5es inclusive com DDD de outros estados, sabemos que \u00e9 chato, mas \u00e9 s\u00f3 por hoje, combinado?<\/p>\n\t\t\t\t\t\t<p class=\"text-center col-md-10 col-12 mx-auto p-0\">Tamb\u00e9m enviamos um e-mail para voc\u00ea, quando puder, confere l\u00e1!<p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<form id=\"conversion-form\" class=\"agz-conversion-form container p-4\" novalidate=\"novalidate\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<h6 class=\"col-md-10 col-12 mx-auto p-0 mt-0\">Solicite uma proposta e conhe\u00e7a nossos servi\u00e7os.<\/h6>\n\t\t\t\t\t\t<p class=\"text-center mb-0 col-md-10 col-12 mx-auto p-0\">Valores - Planos - Benef\u00edcios Inclu\u00eddos - Funcionalidades<\/p>\n\t\t\t\t\t\t<p class=\"text-center col-md-10 col-12 mx-auto p-0\">Tire as suas d\u00favidas - Fazemos quest\u00e3o de ajudar!<p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"row col-md-10 col-12 mx-auto\">\n\t\t\t\t\t\t<div class=\"form-group mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">Nome*<\/label>\n\t\t\t\t\t\t\t<input type=\"text\" name=\"name\" id=\"name\" class=\"w-100 mt-1\" aria-required=\"true\"\n\t\t\t\t\t\t\tplaceholder=\"Digite seu nome\" required autocomplete=\"off\">\n\t\t\t\t\t\t  \t<label id=\"name_error\" class=\"invalid-feedback text-right\" for=\"name\">Este campo \u00e9 requerido.<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"form-group mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">E-mail*<\/label>\n\t\t\t\t\t\t\t<input type=\"email\" name=\"email\" id=\"email\" class=\"w-100 mt-1\" aria-required=\"true\"\n\t\t\t\t\t\t\tplaceholder=\"Digite seu e-mail\" required autocomplete=\"off\">\n\t\t\t\t\t\t\t<label id=\"email_error\" class=\"invalid-feedback text-right\" for=\"email\">Informe um e-mail v\u00e1lido.<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t  \t<div class=\"form-group mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">Telefone*<\/label>\n\t\t\t\t\t\t\t<input type=\"tel\" name=\"phone_number\" id=\"phone_number\" class=\"w-100 mt-1\" placeholder=\"(00) 00000-0000\"\n\t\t\t\t\t\t  required autocomplete=\"off\">\n\t\t\t\t\t\t\t<label id=\"phone_number_error\" class=\"invalid-feedback text-right\" for=\"phone_number\">Informe telefone\n\t\t\t\t\t\t  v\u00e1lido.<\/label>\n\t\t\t\t\t  \t<\/div>\n\t\t\t\t\t\t<div class=\"form-group col-md-5 col-12 mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">Estado*<\/label>\n\t\t\t\t\t\t\t<select name=\"uf\" id=\"uf\" class=\"valid w-100 mt-1\" aria-required=\"true\" required aria-invalid=\"false\">\n\t\t\t\t\t\t\t\t<option value=\"\" disabled selected>Selecione seu estado<\/option>\n\t\t\t\t\t\t\t\t<option value=\"AC\">Acre<\/option>\n\t\t\t\t\t\t\t\t<option value=\"AL\">Alagoas<\/option>\n\t\t\t\t\t\t\t\t<option value=\"AP\">Amap\u00e1<\/option>\n\t\t\t\t\t\t\t\t<option value=\"AM\">Amazonas<\/option>\n\t\t\t\t\t\t\t\t<option value=\"BA\">Bahia<\/option>\n\t\t\t\t\t\t\t\t<option value=\"CE\">Cear\u00e1<\/option>\n\t\t\t\t\t\t\t\t<option value=\"DF\">Distrito Federal<\/option>\n\t\t\t\t\t\t\t\t<option value=\"ES\">Esp\u00edrito Santo<\/option>\n\t\t\t\t\t\t\t\t<option value=\"GO\">Goi\u00e1s<\/option>\n\t\t\t\t\t\t\t\t<option value=\"MA\">Maranh\u00e3o<\/option>\n\t\t\t\t\t\t\t\t<option value=\"MT\">Mato Grosso<\/option>\n\t\t\t\t\t\t\t\t<option value=\"MS\">Mato Grosso do Sul<\/option>\n\t\t\t\t\t\t\t\t<option value=\"MG\">Minas Gerais<\/option>\n\t\t\t\t\t\t\t\t<option value=\"PA\">Par\u00e1<\/option>\n\t\t\t\t\t\t\t\t<option value=\"PB\">Para\u00edba<\/option>\n\t\t\t\t\t\t\t\t<option value=\"PR\">Paran\u00e1<\/option>\n\t\t\t\t\t\t\t\t<option value=\"PE\">Pernambuco<\/option>\n\t\t\t\t\t\t\t\t<option value=\"PI\">Piau\u00ed<\/option>\n\t\t\t\t\t\t\t\t<option value=\"RJ\">Rio de Janeiro<\/option>\n\t\t\t\t\t\t\t\t<option value=\"RN\">Rio Grande do Norte<\/option>\n\t\t\t\t\t\t\t\t<option value=\"RS\">Rio Grande do Sul<\/option>\n\t\t\t\t\t\t\t\t<option value=\"RO\">Rond\u00f4nia<\/option>\n\t\t\t\t\t\t\t\t<option value=\"RR\">Roraima<\/option>\n\t\t\t\t\t\t\t\t<option value=\"SC\">Santa Catarina<\/option>\n\t\t\t\t\t\t\t\t<option value=\"SP\">S\u00e3o Paulo<\/option>\n\t\t\t\t\t\t\t\t<option value=\"SE\">Sergipe<\/option>\n\t\t\t\t\t\t\t\t<option value=\"TO\">Tocantins<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t<label id=\"uf_error\" class=\"invalid-feedback text-right\" for=\"uf\">Este campo \u00e9 requerido.<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"form-group col-md-7 col-12 mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">Cidade*<\/label>\n\t\t\t\t\t\t\t<select name=\"city_code\" id=\"city_code\" class=\"w-100 mt-1 valid\" aria-required=\"true\" required\n\t\t\t\t\t\t\taria-invalid=\"false\">\n\t\t\t\t\t\t\t<option value=\"\" disabled selected>Selecione um estado<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t<label id=\"city_code_error\" class=\"invalid-feedback text-right\" for=\"city_code\">Este campo \u00e9 requerido.<\/label>\n\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t<div class=\"form-group col-md-6 col-12 mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">Qual servi\u00e7o deseja?*<\/label>\n\t\t\t\t\t\t\t<select name=\"service\" id=\"service\" class=\"w-100 mt-1 valid\" aria-required=\"true\" required\n\t\t\t\t\t\t\taria-invalid=\"false\">\n\t\t\t\t\t\t\t\t<option value=\"\" disabled selected>Selecione o servi\u00e7o<\/option>\n\t\t\t\t\t\t\t\t<option value=\"migracao\">Trocar de contador<\/option>\n\t\t\t\t\t\t\t\t<option value=\"abertura\">Abrir uma empresa<\/option>\n\t\t\t\t\t\t\t\t<option value=\"mei\">Contabilidade para MEI<\/option>\n                    \t\t\t<option value=\"mei-abertura\">Abertura MEI<\/option>\n                    \t\t\t<option value=\"mei-me\">Transformar de MEI para ME<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t<label id=\"service_error\" class=\"invalid-feedback text-right\" for=\"service\">Este campo \u00e9 requerido.<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"form-group col-md-6 col-12 mb-2\">\n\t\t\t\t\t\t\t<label class=\"title\">Qual atividade da sua empresa?*<\/label>\n\t\t\t\t\t\t\t<select name=\"company_type\" id=\"company_type\" class=\"w-100 mt-1 valid\" aria-required=\"true\" required\n\t\t\t\t\t\t\taria-invalid=\"false\">\n\t\t\t\t\t\t\t\t<option value=\"\" disabled selected>Selecione a \u00e1rea de atua\u00e7\u00e3o da sua empresa?<\/option>\n\t\t\t\t\t\t\t\t<option value=\"comercio\">Com\u00e9rcio<\/option>\n\t\t\t\t\t\t\t\t<option value=\"servico\">Servi\u00e7o<\/option>\n\t\t\t\t\t\t\t\t<option value=\"comercio servico\">Com\u00e9rcio e Servi\u00e7o<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t<label id=\"company_type_error\" class=\"invalid-feedback text-right\" for=\"company_type\">Este campo \u00e9 requerido.<\/label>\n\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t<\/div>\t\t\t\t\n\t\t\t\t\t<div class=\"w-100 text-center\">\n\t\t\t\t\t\t<button id=\"btn-submit-contact\" type=\"submit\" class=\"btn my-4 shadow-none text-uppercase\">CLIQUE E RECEBA NOSSO CONTATO<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<p class=\"text-center col-md-10 col-12 m-0 mx-auto p-0\">Seus dados est\u00e3o seguros conosco. Ao solicitar uma proposta, voc\u00ea concorda com nossos <a target=\"_blank\" href=\"https:\/\/agilize.com.br\/termos-de-uso\">Termos de uso<\/a> e <a target=\"_blank\" href=\"https:\/\/agilize.com.br\/politica-de-privacidade\">Pol\u00edtica de privacidade<\/a>.<p>\n\t\t\t\t<\/form>\n\t\t\t<\/aside>\n\t\t\t<script>\n\t\t\t\tfunction getApiUrl() {\n\t\t\t\t\treturn \"https:\/\/api-growth.agilize.com.br\";\n\t\t\t\t}\n\t\t\t\tfunction validateFormInputs(email, phone) {\n\t\t\t\t\tif (email && phone) {\n\t\t\t\t\t\tvar regexEmail = \/^([\\w\\.\\-]+)@([\\w\\-]+)((\\.(\\w){2,3})+)$\/m;\n\t\t\t\t\t\tvar regexAllSame = \/^(\\d)(?!\\1+$)\\d{11}$\/;\n\t\t\t\t\t\tif (regexEmail.test(email) && (phone.length == 10 || phone.length == 11)) {\n\t\t\t\t\t\t\treturn true;\n\t\t\t\t\t\t}\n\t\t\t\t\t\treturn false;\n\t\t\t\t\t}\n\t\t\t\t\treturn false;\n\t\t\t\t}\n\t\t\t\tdocument.getElementById(\"phone_number\").addEventListener(\"keyup\", function (event) {\n\t\t\t\t\tvar value = event.target.value.replace(\/\\D\/g, \"\");\n\t\t\t\t\tvalue = value.replace(\/^0\/, \"\");\n\t\t\t\t\tif (value.length > 10) {\n\t\t\t\t\t\tvalue = value.replace(\/^(\\d\\d)(\\d{5})(\\d{4}).*\/, \"($1) $2-$3\");\n\t\t\t\t\t} else if (value.length > 5) {\n\t\t\t\t\t\tvalue = value.replace(\/^(\\d\\d)(\\d{4})(\\d{0,4}).*\/, \"($1) $2-$3\");\n\t\t\t\t\t} else if (value.length > 2) {\n\t\t\t\t\t\tvalue = value.replace(\/^(\\d\\d)(\\d{0,5})\/, \"($1) $2\");\n\t\t\t\t\t} else {\n\t\t\t\t\t\tvalue = value.replace(\/^(\\d*)\/, \"($1\");\n\t\t\t\t\t}\n\t\t\t\t\tevent.target.value = value;\n\t\t\t\t});\n\t\t\t\tdocument.getElementById(\"conversion-form\").addEventListener(\"submit\", function (event) {\n\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\tevent.stopPropagation();\n\t\t\t\t\tdocument.getElementById(\"conversion-form\").classList.add(\"was-validated\");\n\t\t\t\t\tvar name = document.getElementById(\"name\").value || undefined;\n\t\t\t\t\tvar email = document.getElementById(\"email\").value || undefined;\n\t\t\t\t\tvar service = document.getElementById(\"service\").value || undefined;\n\t\t\t\t\tvar company_type = document.getElementById(\"company_type\").value || undefined;\n\t\t\t\t\tvar phone_number = document.getElementById(\"phone_number\").value || undefined;\n\t\t\t\t\tvar city_code = document.getElementById(\"city_code\").value || undefined;\n\t\t\t\t\tvar tracking = localStorage.LDTKR_AGZ;\n\t\t\t\t\tif (phone_number) {\n\t\t\t\t\t\tphone_number = phone_number.replace(\/\\D+\/g, \"\");\n\t\t\t\t\t}\n\t\t\t\t\tif (!validateFormInputs(email, phone_number)) {\n\t\t\t\t\t\treturn null;\n\t\t\t\t\t}\n\t\t\t\t\tif (name == \"\" || name == undefined || email == \"\" || email == undefined || service == \"\" || service == \t\t\t\t\t\tundefined || company_type == \"\" || company_type == undefined || phone_number == \"\" || phone_number \t\t\t\t\t\t\t== undefined || city_code == \"\" || city_code == undefined){\n\t\t\t\t\t\treturn null;\n\t\t\t\t\t}\n\t\t\t\t\tif (company_type) {\n\t\t\t\t\t\tcompany_type = company_type.split(\" \");\n\t\t\t\t\t}\n\t\t\t\t\tvar btnSubmit = document.getElementById(\"btn-submit-contact\");\n\t\t\t\t\tbtnSubmit.disabled = true;\n\t\t\t\t\tbtnSubmit.innerHTML = \"Enviando...\";\n\t\t\t\t\tvar tracking = agzTKRV2.getTrackerData();\n\t\t\t\t\tvar objectData = {\n\t\t\t\t\t\tid: agzTKRV2.getID(),\n\t\t\t\t\t\tname,\n\t\t\t\t\t\temail,\n\t\t\t\t\t\tphone_number,\n\t\t\t\t\t\tservice_id: getServiceID(service),\n\t\t\t\t\t\tcity_id: parseInt(city_code),\n\t\t\t\t\t\tcompany_types: getCompanyTypesIDs(company_type),\n\t\t\t\t\t\tscore: agzTKRV2.getScore(),\n\t\t\t\t\t\ttracking: {\n\t\t\t\t\t\t\t...tracking,\n\t\t\t\t\t\t},\n\t\t\t\t\t\tlead_navigation: agzTKRV2.getNavigationHistoryData(),\n\t\t\t\t\t\tconversion_at: new Date(),\n\t\t\t\t\t}\n\t\t\t\t\tif (objectData) {\n\t\t\t\t\t\tfetch(getApiUrl() + \"\/v1\/leads\", {\n\t\t\t\t\t\t\tmethod: \"POST\",\n\t\t\t\t\t\t\theaders: {\n\t\t\t\t\t\t\t\t\"Accept\": \"application\/json\",\n\t\t\t\t\t\t\t\t\"Content-Type\": \"application\/json\"\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\tbody: JSON.stringify(objectData)\n\t\t\t\t\t\t}).then(response => response.json())\n\t\t\t\t\t\t\t.then(result => {\n\t\t\t\t\t\t\t\tdocument.getElementById(\"conversion-form\").style.display = \"none\";\n\t\t\t\t\t\t\t\tdocument.getElementById(\"agz-conversion-form-success\").style.display = \"block\";\n\t\t\t\t\t\t\t\tdocument.getElementById(\"name\").value = \"\";\n\t\t\t\t\t\t\t\tdocument.getElementById(\"email\").value = \"\";\n\t\t\t\t\t\t\t\tdocument.getElementById(\"phone_number\").value = \"\";\n\t\t\t\t\t\t\t\tdocument.getElementById(\"uf\").value = \"\";\n\t\t\t\t\t\t\t\tdocument.getElementById(\"city_code\").value = \"\";\n\t\t\t\t\t\t\t\tbtnSubmit.disabled = false;\n\t\t\t\t\t\t\t\tbtnSubmit.innerHTML = \"CLIQUE E RECEBA NOSSO CONTATO\";\n\t\t\t\t\t\t\t})\n\t\t\t\t\t}\n\t\t\t\t\tagzTKRV2.resetTracker().then(()=> console.info(\"identifier updated\"));\n\t\t\t\t\tgtag(\"event\", \"conversao_lead_novo_comercial_formulario_blogpost\");\n\t\t\t\t});\n\t\t\t\tdocument.getElementById(\"uf\").addEventListener(\"change\", function (event) {\n\t\t\t\t\tvar uf = event.target.value;\n\t\t\t\t\tvar url = getApiUrl() + \"\/v1\/outside\/cities\/uf\/\" + uf;\n\t\t\t\t\tvar citySelect = document.getElementById(\"city_code\");\n\t\t\t\t\tcitySelect.options.length = 0;\n\t\t\t\t\tcitySelect.add(new Option(\"Buscando cidades...\", \"\"));\n\t\t\t\t\tfetch(url).then(response => response.json()).then(result => {\n\t\t\t\t\t\tif (result.success) {\n\t\t\t\t\t\t\tcitySelect.options.length = 0;\n\t\t\t\t\t\t\tcitySelect.add(new Option(\"Selecione sua cidade\", \"\"));\n\t\t\t\t\t\t\tfor (var i = 0; i < result.payload.length; i++) {\n\t\t\t\t\t\t\t\tcitySelect.add(new Option(result.payload[i].name, result.payload[i].id));\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\talert(\"N\u00e3o foi possivel carregas as cidades, tente novamente.\");\n\t\t\t\t\t\t}\n\t\t\t\t\t}).catch(() => alert(\"N\u00e3o foi possivel carregas as cidades, tente novamente.\"))\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\n\n\n\n<h3 class=\"wp-block-heading\">Registrar a empresa na OAB e na Junta Comercial<\/h3>\n\n\n\n<p>Ap\u00f3s escolher a estrutura jur\u00eddica adequada, o advogado precisa<strong> registrar a empresa junto \u00e0 Ordem dos Advogados do Brasil (OAB)<\/strong>, que regula as atividades advocat\u00edcias no pa\u00eds.<\/p>\n\n\n\n<p>No caso da Sociedade Unipessoal de Advocacia, o registro pode ser feito diretamente na OAB, enquanto outras estruturas podem tamb\u00e9m requerer inscri\u00e7\u00e3o na Junta Comercial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solicitar o CNPJ na Receita Federal<\/h3>\n\n\n\n<p>Com o registro da empresa aprovado na OAB, o advogado deve <a href=\"https:\/\/agilize.com.br\/blog\/abertura-de-empresa\/como-abrir-um-cnpj\/\">obter o CNPJ<\/a> junto \u00e0 Receita Federal.<\/p>\n\n\n\n<p>Isso \u00e9 essencial para que a empresa seja formalmente constitu\u00edda e tenha acesso ao Simples Nacional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Escolher o Simples Nacional como regime tribut\u00e1rio<\/h3>\n\n\n\n<p>Assim que a empresa obtiver o CNPJ, o advogado precisa solicitar a ades\u00e3o ao Simples Nacional.<\/p>\n\n\n\n<p>Isso pode ser feito diretamente pelo <a href=\"https:\/\/www8.receita.fazenda.gov.br\/simplesnacional\/\" target=\"_blank\" rel=\"noopener\">Portal do Simples Nacional<\/a>, que centraliza todos os processos necess\u00e1rios para a ades\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Verificar o enquadramento na tabela do Simples Nacional<\/h3>\n\n\n\n<p>Dentro do Simples Nacional, os advogados se enquadram no <strong>Anexo IV da tabela de tributa\u00e7\u00e3o<\/strong>, espec\u00edfico para prestadores de servi\u00e7os regulamentados, como advocacia, arquitetura e medicina.<\/p>\n\n\n\n<p>Entre outras coisas, esse anexo define as al\u00edquotas e a base de c\u00e1lculo do imposto conforme o faturamento mensal da empresa.<\/p>\n\n\n\n<p>Com isso, o advogado consegue aderir ao Simples Nacional, aproveitando os benef\u00edcios de uma tributa\u00e7\u00e3o mais simples e econ\u00f4mica, adequada para sua atividade profissional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"O-que-um-advogado-precisa-para-abrir-uma-empresa\">O que um advogado precisa para abrir uma empresa?<\/h2>\n\n\n\n<p>Para abrir uma empresa, um advogado precisa atender a alguns requisitos espec\u00edficos que garantem a regularidade de sua atua\u00e7\u00e3o profissional:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Registro na OAB<\/strong>: todo advogado que deseja abrir uma empresa precisa estar devidamente registrado na Ordem dos Advogados do Brasil (OAB).<\/li>\n\n\n\n<li><strong>Escolha da natureza jur\u00eddica<\/strong>: o profissional deve escolher a forma jur\u00eddica mais adequada, como a Sociedade Unipessoal ou Sociedade Simples de Advogados.<\/li>\n\n\n\n<li><strong>Inscri\u00e7\u00e3o no CNPJ<\/strong>: ap\u00f3s definir a natureza jur\u00eddica, \u00e9 necess\u00e1rio solicitar o CNPJ junto \u00e0 Receita Federal.<\/li>\n\n\n\n<li><strong>Registro na Junta Comercial ou OAB<\/strong>: em algumas modalidades, como a Sociedade Unipessoal, o registro pode ser feito diretamente pela OAB.<\/li>\n\n\n\n<li><strong>Defini\u00e7\u00e3o do regime tribut\u00e1rio<\/strong>: \u00e9 fundamental que o advogado escolha o <a href=\"https:\/\/agilize.com.br\/blog\/empreendedorismo\/regime-tributario\/\">regime tribut\u00e1rio<\/a> mais vantajoso para sua empresa, sendo o Simples Nacional uma das op\u00e7\u00f5es poss\u00edveis.<\/li>\n<\/ul>\n\n\n\n<p>\u00c9 importante lembrar que cada regime tem vantagens e desvantagens dependendo do faturamento e das caracter\u00edsticas da empresa<\/p>\n\n\n\n<p>Com o CNPJ ativo, o advogado pode aproveitar benef\u00edcios como a emiss\u00e3o de notas fiscais, a ades\u00e3o a regimes tribut\u00e1rios simplificados (como o Simples Nacional) e uma melhor gest\u00e3o financeira.<\/p>\n\n\n\n<p>Veja tamb\u00e9m o que \u00e9 o CNPJ inativo:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CNPJ Inativo: entenda o que \u00e9\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/U-Z2To89RQA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Quais-as-vantagens-de-ter-CNPJ-como-advogado\">Quais as vantagens de ter CNPJ como advogado?<\/h2>\n\n\n\n<p>Entre os principais pontos positivos, podemos citar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Emiss\u00e3o de nota fiscal<\/strong>: com o CNPJ, o advogado pode emitir notas fiscais, o que facilita o atendimento a empresas e clientes maiores;<\/li>\n\n\n\n<li><strong>Redu\u00e7\u00e3o de impostos<\/strong>: o Simples Nacional oferece uma tributa\u00e7\u00e3o menor e simplificada, diminuindo a carga tribut\u00e1ria do advogado;<\/li>\n\n\n\n<li><strong>Credibilidade<\/strong>: ter um CNPJ confere mais credibilidade ao profissional, facilitando a capta\u00e7\u00e3o de novos clientes e aumentando a confian\u00e7a do mercado;<\/li>\n\n\n\n<li><strong>Acesso a benef\u00edcios banc\u00e1rios<\/strong>: empresas possuem acesso a linhas de <a href=\"https:\/\/agilize.com.br\/blog\/gestao-financeira\/credito-para-empresas\/\">cr\u00e9dito<\/a> e benef\u00edcios espec\u00edficos que n\u00e3o est\u00e3o dispon\u00edveis para pessoas f\u00edsicas, permitindo ao advogado obter melhores condi\u00e7\u00f5es para investir em seu escrit\u00f3rio.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"AGILIZE CONTABILIDADE ONLINE\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9Z5_wYezT04?start=3&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Tenha-um-CNPJ-para-advogado-sem-burocracias\">Tenha um CNPJ para advogado sem burocracias<\/h2>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 sabe que \u00e9 negativa a afirma\u00e7\u00e3o de que advogado pode ser MEI, est\u00e1 na hora de formalizar sua atividade e obter um CNPJ pode parecer complicado, mas com a Agilize, todo o processo se torna simples e descomplicado.&nbsp;<\/p>\n\n\n\n<p>A Agilize \u00e9 especialista em abertura de CNPJs e regulariza\u00e7\u00e3o de empresas, incluindo as espec\u00edficas para advogados, como a Sociedade Unipessoal de Advocacia (SUA).<\/p>\n\n\n\n<p><strong>Deixe as burocracias com quem entende do assunto!<\/strong> A equipe da Agilize cuida de todas as etapas, desde o registro na OAB at\u00e9 a ades\u00e3o ao Simples Nacional, garantindo que sua empresa esteja totalmente regularizada e pronta para atuar.<\/p>\n\n\n\n<p>Clique no banner e formalize agora a sua empresa!<\/p>\n\n\n\n\n\t\t\t<style>\n\t\t\t\t.btn-agz-banner{\n\t\t\t\t\tuser-select: none;\n\t\t\t\t\tdisplay: inline-block;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\ttext-decoration: none;\n\t\t\t\t\tvertical-align: middle;\n\t\t\t\t\tcursor: pointer;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t\talign-self: center;\n\t\t\t\t\topacity: 1;\n\t\t\t\t\ttransition: all .25s ease-in-out;\n\t\t\t\t\tmargin: 1rem auto;\n\t\t\t\t}\n\t\t\t\t.btn-agz-banner:hover {\n\t\t\t\t\topacity: 0.9;\n\t\t\t\t\ttransition: all .25s ease-in-out;\n\t\t\t\t}\n\t\t\t\t.img-agz-banner {\n\t\t\t\t\toverflow: auto;\n\t\t\t\t\tborder-radius: 0.5rem;\n\t\t\t\t}\n\t\t\t<\/style>\n\t\t<a id=\"btn-cta-banner\" class=\"btn-agz-banner\" onclick=\"gtag('event', 'clicou_banner_blogpost');\"  title=\"Quero falar com a Agilize\" ><img decoding=\"async\" class=\"img-agz-banner\" src=\"https:\/\/agilize.com.br\/blog\/wp-content\/uploads\/2023\/12\/banner_2-2.webp\"\/><\/a>\n\t\t\t<script>\n\t\t\t\tvar popUpId = \"agz-modal-conversion-form\";\n\t\t\t\tdocument.getElementById(\"btn-cta-banner\").addEventListener(\"click\", function (event) {\n\t\t\t\t\tdocument.getElementById(popUpId).style.display = \"flex\";\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t\n\t\t\n\n\n\n<h3 class=\"wp-block-heading\">Veja outros conte\u00fados selecionados para voc\u00ea!<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"https:\/\/agilize.com.br\/blog\/abertura-de-empresa\/tipos-de-empresa\/\">Tipos de empresa: conhe\u00e7a os principais e qual escolher!<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/agilize.com.br\/blog\/empreendedorismo\/regime-tributario\/\">Regime tribut\u00e1rio: descubra em qual a sua empresa se encaixa<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/agilize.com.br\/blog\/abertura-de-empresa\/como-abrir-uma-empresa-simples\/\">Passo a passo de como abrir uma empresa Simples Nacional<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>A d\u00favida &#8220;advogado pode ser MEI?&#8221; \u00e9 comum entre profissionais da advocacia que desejam formalizar suas atividades e obter os benef\u00edcios de ter um CNPJ. Nesse contexto, o regime de Microempreendedor Individual (MEI) oferece vantagens atrativas, como baixos custos com impostos e menos burocracia, mas ser\u00e1 que advogados podem se enquadrar nessa categoria? Vamos explorar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,328],"tags":[353],"class_list":["post-37357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abrir-sua-empresa","category-tipos-de-empresa","tag-contabilidadeparaadvogados"],"_links":{"self":[{"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/posts\/37357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/comments?post=37357"}],"version-history":[{"count":7,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/posts\/37357\/revisions"}],"predecessor-version":[{"id":42578,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/posts\/37357\/revisions\/42578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/media\/42474"}],"wp:attachment":[{"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/media?parent=37357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/categories?post=37357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agilize.com.br\/blog\/wp-json\/wp\/v2\/tags?post=37357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}